{"id":905,"date":"2023-05-23T13:11:27","date_gmt":"2023-05-23T11:11:27","guid":{"rendered":"https:\/\/www.irlippok.de\/lortzingart\/?p=905"},"modified":"2023-06-13T07:59:33","modified_gmt":"2023-06-13T05:59:33","slug":"renate-folkers-sonntagsmatinee","status":"publish","type":"post","link":"https:\/\/www.irlippok.de\/lortzingart\/2023\/05\/23\/renate-folkers-sonntagsmatinee\/","title":{"rendered":"RENATE FOLKERS Sonntagsmatinee"},"content":{"rendered":"\n<p><br><strong>Lesung mit der Autorin <br>11. Juni 2023 um 11:30 Uhr<\/strong><br><strong>Von Liebe &amp; andren Katastrophen<\/strong> lautet das Motto, zu dem die aus Nordfriesland stammende <strong>Autorin Renate Folkers<\/strong> ihren G\u00e4sten Geschichten, Gedichte und kriminelle Entgleisungen in heiterer Form zu Geh\u00f6r bringen m\u00f6chte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1006\" height=\"1024\" src=\"https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG_7064-1006x1024.jpeg\" alt=\"\" class=\"wp-image-906\" srcset=\"https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG_7064-1006x1024.jpeg 1006w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG_7064-295x300.jpeg 295w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG_7064-768x782.jpeg 768w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG_7064-1509x1536.jpeg 1509w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG_7064-2012x2048.jpeg 2012w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2023\/05\/IMG_7064-1568x1596.jpeg 1568w\" sizes=\"auto, (max-width: 1006px) 100vw, 1006px\" \/><\/figure>\n\n\n\n<p>Renate Folkers wurde 1950 auf Nordstrand geboren. \u00dcber 50 Jahre lebte die Autorin in ihrer nordfriesischen Heimat. Nach ihrer Ausbildung in der Kommunalverwaltung blieb sie mit kurzen Unterbrechungen dem \u00f6ffentlichen Dienst treu.<br>Mit dem Schreiben begann sie 2009, mit dem Ausstieg aus dem Berufsleben. \u201eMeine ersten Texte entstanden, als ich schwierige Lebenssituationen zu verarbeiten hatte. Da war das Schreiben sehr hilfreich, ein gutes Ventil und der Einstieg in ein spannendes Autorenleben\u201c, so die Schriftstellerin.<br>Insgesamt hat Folkers in unterschiedlichen Verlagen drei Kriminalromane ver\u00f6ffentlicht, zwei in hochdeutscher, einer in plattdeutscher Sprache.<br>2019 erschien die Anthologie SPUREN SICHERN mit Lieblingsgedichten und Geschichten. \u201eDieses Buch ist den Menschen gewidmet, die nicht verlernt haben den Zauber der sch\u00f6nen Dinge im Leben wahrzunehmen und sich an ihnen zu freuen,\u201c sagt Folkers. Die Autorin steht nach der Lesung bereit, mit den G\u00e4sten ins Gespr\u00e4ch zu kommen und Fragen zu beantworten.<br><em>Man kann&nbsp; sich auf einen heiteren literarischen Spaziergang in Lyrik und Prosa freuen&#8230;<\/em><br><br><strong>Gef\u00f6rdert durch das Kulturb\u00fcro der Landeshauptstadt Hannover<\/strong><br>Eintritt frei &#8211; gern Hutspende&nbsp;&nbsp; <br>Bitte Platzreservierung unter Tel. 0179-963 4114<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lesung mit der Autorin 11. Juni 2023 um 11:30 UhrVon Liebe &amp; andren Katastrophen lautet das Motto, zu dem die aus Nordfriesland stammende Autorin Renate Folkers ihren G\u00e4sten Geschichten, Gedichte und kriminelle Entgleisungen in heiterer Form zu Geh\u00f6r bringen m\u00f6chte. Renate Folkers wurde 1950 auf Nordstrand geboren. \u00dcber 50 Jahre lebte die Autorin in ihrer&hellip; <a class=\"more-link\" href=\"https:\/\/www.irlippok.de\/lortzingart\/2023\/05\/23\/renate-folkers-sonntagsmatinee\/\"><span class=\"screen-reader-text\">RENATE FOLKERS Sonntagsmatinee<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-905","post","type-post","status-publish","format-standard","hentry","category-lesungkulturbuero","category-start","entry"],"_links":{"self":[{"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/posts\/905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/comments?post=905"}],"version-history":[{"count":2,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/posts\/905\/revisions"}],"predecessor-version":[{"id":915,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/posts\/905\/revisions\/915"}],"wp:attachment":[{"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/media?parent=905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/categories?post=905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/tags?post=905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}