{"id":1109,"date":"2024-06-08T10:45:37","date_gmt":"2024-06-08T08:45:37","guid":{"rendered":"https:\/\/www.irlippok.de\/lortzingart\/?p=1109"},"modified":"2024-09-23T18:26:11","modified_gmt":"2024-09-23T16:26:11","slug":"letzte-ausfahrt-hiddensee","status":"publish","type":"post","link":"https:\/\/www.irlippok.de\/lortzingart\/2024\/06\/08\/letzte-ausfahrt-hiddensee\/","title":{"rendered":"LETZTE AUSFAHRT HIDDENSEE"},"content":{"rendered":"\n<p><strong>Einladung zur Autoren-Krimilesung mit Burkhard Wetekam\u00a0<\/strong><br><strong>Moderation: Jan Ehlert<br><\/strong><strong>Sonntag, 22. September 2024,\u00a017 Uhr<br><br><\/strong><strong>Eintritt frei &#8211; gern Hutspende<\/strong><strong><br>Platzreservierung unter Tel. 0179 963 4114 <\/strong><strong>Gef\u00f6rdert durch das Kulturb\u00fcro der Landeshauptstadt Hannover<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"958\" height=\"1024\" src=\"https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2024\/09\/Burkhard-Wetekam-Foto-Werner-Musterer-958x1024.jpg\" alt=\"\" class=\"wp-image-1095\" style=\"width:328px;height:auto\" srcset=\"https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2024\/09\/Burkhard-Wetekam-Foto-Werner-Musterer-958x1024.jpg 958w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2024\/09\/Burkhard-Wetekam-Foto-Werner-Musterer-281x300.jpg 281w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2024\/09\/Burkhard-Wetekam-Foto-Werner-Musterer-768x821.jpg 768w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2024\/09\/Burkhard-Wetekam-Foto-Werner-Musterer-1437x1536.jpg 1437w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2024\/09\/Burkhard-Wetekam-Foto-Werner-Musterer-1568x1676.jpg 1568w, https:\/\/www.irlippok.de\/lortzingart\/wp-content\/uploads\/sites\/2\/2024\/09\/Burkhard-Wetekam-Foto-Werner-Musterer.jpg 1573w\" sizes=\"auto, (max-width: 958px) 100vw, 958px\" \/><figcaption class=\"wp-element-caption\"><strong>Foto Burkhard Wetekam&nbsp; Fotograf: Werner Musterer<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p>LETZTE AUSFAHRT HIDDENSEE ist der f\u00fcnfte Krimi mit dem Privatermittler Tom Brauer. Ein lang zur\u00fcckliegendes Verbrechen, eine schwierige Freundschaft und ganz viel Insel \u2013 das alles steckt im neuen Krimi von Burkhard Wetekam.<br>Im Gespr\u00e4ch mit Jan Ehlert stellt der Autor das Buch am 22. September im Atelier LortzingArt vor.<br><strong>Burkhard Wetekam<\/strong> lebt als Autor und Journalist in Hannover. Seit 2015 schreibt er an einer Reihe von Kriminalromanen, die an der Ostsee spielen.&nbsp;<br>Er verfasst auch Erz\u00e4hlungen, H\u00f6rspiele und Theatertexte und hat daf\u00fcr mehrere Literaturpreise und Stipendien erhalten.&nbsp;<br>Seit 2023 ist er Gesch\u00e4ftsf\u00fchrer beim Autor:innenzentrum Hannover.<br><strong>Jan Ehlert<\/strong> (Moderation) arbeitet als Redakteur bei NDR Kultur und ist unter anderem Host beim beliebten B\u00fccher-Podcast eat.read.sleep.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einladung zur Autoren-Krimilesung mit Burkhard Wetekam\u00a0Moderation: Jan EhlertSonntag, 22. September 2024,\u00a017 Uhr Eintritt frei &#8211; gern HutspendePlatzreservierung unter Tel. 0179 963 4114 Gef\u00f6rdert durch das Kulturb\u00fcro der Landeshauptstadt Hannover LETZTE AUSFAHRT HIDDENSEE ist der f\u00fcnfte Krimi mit dem Privatermittler Tom Brauer. Ein lang zur\u00fcckliegendes Verbrechen, eine schwierige Freundschaft und ganz viel Insel \u2013 das alles&hellip; <a class=\"more-link\" href=\"https:\/\/www.irlippok.de\/lortzingart\/2024\/06\/08\/letzte-ausfahrt-hiddensee\/\"><span class=\"screen-reader-text\">LETZTE AUSFAHRT HIDDENSEE<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1109","post","type-post","status-publish","format-standard","hentry","category-lesungkulturbuero","entry"],"_links":{"self":[{"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/posts\/1109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/comments?post=1109"}],"version-history":[{"count":2,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/posts\/1109\/revisions"}],"predecessor-version":[{"id":1111,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/posts\/1109\/revisions\/1111"}],"wp:attachment":[{"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/media?parent=1109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/categories?post=1109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irlippok.de\/lortzingart\/wp-json\/wp\/v2\/tags?post=1109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}